{"id":3291,"date":"2023-11-13T16:03:03","date_gmt":"2023-11-13T19:03:03","guid":{"rendered":"https:\/\/aulaabierta.unahur.edu.ar\/?p=3291"},"modified":"2023-11-13T16:12:43","modified_gmt":"2023-11-13T19:12:43","slug":"emir-sader-en-la-unahur","status":"publish","type":"post","link":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/2023\/11\/13\/emir-sader-en-la-unahur\/","title":{"rendered":"Emir Sader en la UNAHUR"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El pasado viernes 10 de noviembre, el fil\u00f3sofo y polit\u00f3logo Emir Sader visit\u00f3 la Universidad Nacional de Hurlingham (UNAHUR).<\/h2>\n\n\n\n<p>La actividad estuvo dirigida a estudiantes de la Maestr\u00eda en Pol\u00edtica Educativa y el Doctorado en Educaci\u00f3n, docentes y no docentes. <strong>Walter Wallach<\/strong>, vicerrector-rector en ejercicio de la UNAHUR, agradeci\u00f3 a <strong>Yamile Socolovsky<\/strong>, secretaria de G\u00e9nero de la CTA de les Trabajadorxs y secretaria de Relaciones Internacionales de CONADU, quien <strong>hizo posible la presencia de Sader en la universidad<\/strong>. \u201cEmir quer\u00eda conocer una universidad del conurbano bonaerense y pens\u00f3 en nosotros\u201d, destac\u00f3 Wallach. Luego se\u00f1al\u00f3 que las y los estudiantes presentes de la Maestr\u00eda y el Doctorado \u201cson profesoras y profesores de la escuela p\u00fablica primaria y secundaria de la regi\u00f3n que hicieron aqu\u00ed su Licenciatura en Educaci\u00f3n\u201d.<\/p>\n\n\n\n<p>Sader, acompa\u00f1ado por autoridades, fue invitado a recorrer distintos espacios de la UNAHUR mientras recib\u00eda datos concretos sobre el n\u00famero de estudiantes y de carreras dictadas. <strong>\u201cAcostumbrado a dar conferencias frente a grandes audiencias, lo que se intent\u00f3 fue organizar su visita para que pudiera conocer a la comunidad universitaria de nuestra joven UNAHUR y recibir testimonios de estudiantes y trabajadores\/as docentes y nodocentes acerca de la experiencia que se lleva adelante en una universidad del Conurbano de la Provincia de Buenos Aires\u201d<\/strong>, cont\u00f3 Leonardo Mottillo, secretario general de SUDHUR. \u201cEl conversatorio estuvo dirigido a una audiencia \u00edntima, conformada, en primer lugar, por estudiantes de posgrado del Instituto de Educaci\u00f3n y por compa\u00f1eros\/as docentes y nodocentes convocados por sus organizaciones colectivas SUDHUR y ATUNH\u201d, agreg\u00f3.<\/p>\n\n\n\n<p>Sader subray\u00f3 que, hasta hace poco tiempo, en el nordeste de Brasil hab\u00eda que elegir qu\u00e9 miembro de la familia iba a estudiar al sur del pa\u00eds. \u201cHoy, el nordeste, la regi\u00f3n m\u00e1s pobre, tiene m\u00e1s estudiantes universitarios que el sur rico\u201d, dijo. Tambi\u00e9n se refiri\u00f3 a la importancia de las elecciones del 19 de noviembre: <strong>\u201cImag\u00ednense un nuevo gobierno progresista: M\u00e9xico, Colombia, Brasil y Argentina. Los cuatro pa\u00edses m\u00e1s grandes de Am\u00e9rica Latina unidos\u201d<\/strong>.<\/p>\n\n\n\n<p>@AAUNAHUR<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado viernes 10 de noviembre, el fil\u00f3sofo y polit\u00f3logo Emir Sader visit\u00f3 la Universidad Nacional de Hurlingham (UNAHUR). La actividad estuvo dirigida a estudiantes de la Maestr\u00eda en Pol\u00edtica Educativa y el Doctorado en Educaci\u00f3n, docentes y no docentes. Walter Wallach, vicerrector-rector en ejercicio de la UNAHUR, agradeci\u00f3 a Yamile Socolovsky, secretaria de G\u00e9nero [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3293,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[7],"tags":[578,635,336,102,335,140,147],"class_list":["post-3291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-doctorado-en-educacion","tag-emir-sader","tag-leonardo-motillo","tag-maestria-en-politica-educativa","tag-sudhur","tag-unahur","tag-walter-wallach"],"_links":{"self":[{"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/3291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=3291"}],"version-history":[{"count":2,"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/3291\/revisions"}],"predecessor-version":[{"id":3294,"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/3291\/revisions\/3294"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/3293"}],"wp:attachment":[{"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=3291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=3291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=3291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}