{"id":3303,"date":"2023-11-21T14:50:23","date_gmt":"2023-11-21T17:50:23","guid":{"rendered":"https:\/\/aulaabierta.unahur.edu.ar\/?p=3303"},"modified":"2023-11-21T14:50:24","modified_gmt":"2023-11-21T17:50:24","slug":"un-noviembre-por-mas-esi","status":"publish","type":"post","link":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/2023\/11\/21\/un-noviembre-por-mas-esi\/","title":{"rendered":"Un noviembre por m\u00e1s ESI"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El s\u00e1bado 11 de noviembre se desarroll\u00f3 la Feria ESI, a cargo del Equipo ESI de la Universidad Nacional de Hurlingham (UNAHUR). Tal como sucedi\u00f3 en julio de 2023, se compartieron m\u00e1s de cien propuestas l\u00fadicas, intervenciones art\u00edsticas y producciones realizadas por estudiantes. Adem\u00e1s, el lunes 13 de noviembre, el Movimiento Federal XM\u00e1sESI present\u00f3 la campa\u00f1a Democracia y ESI: 40 a\u00f1os, 40 razones.<\/h2>\n\n\n\n<p>La <strong>Feria ESI es la instancia de evaluaci\u00f3n de las dos materias de la UNAHUR<\/strong> sobre educaci\u00f3n sexual integral: una espec\u00edfica para la formaci\u00f3n en docencia universitaria y otra que integra la oferta de materias optativas y transversales a los cuatro institutos. El objetivo de la feria es que puedan <strong>mostrarse a la comunidad las reflexiones que se elaboran dentro de las aulas<\/strong>. Las y los estudiantes puede elegir entre varios formatos para exhibir sus producciones: intervenciones art\u00edsticas y producciones audiovisuales, literarias, l\u00fadicas o radiales.<\/p>\n\n\n\n<p>La sexta edici\u00f3n de la feria cont\u00f3 con algunas novedades. \u201c<strong>El 25 de julio tuvimos una v\u00edctima de femicidio del Profesorado Universitario de Ingl\u00e9s de nuestra universidad, Nancy L\u00f3pez Gota<\/strong>, y se le hizo un homenaje\u201d, resalt\u00f3 Mariana Lavari, docente, investigadora y coordinadora del equipo de ESI de la UNAHUR. \u201cFue una situaci\u00f3n muy dolorosa que vivimos. Esta vez nos toc\u00f3 de cerca. Una compa\u00f1era de Nancy cant\u00f3 la canci\u00f3n \u2018Sin miedo\u2019 y otras contaron c\u00f3mo era Nancy. <strong>Le dieron entidad a su ser, a vez que repudiaron las violencias por razones de g\u00e9nero y los femicidios<\/strong>\u201d, cont\u00f3 Lavari.<\/p>\n\n\n\n<p>Estuvo presente la biblioteca Cervantes de la UNAHUR con un espacio dedicado a la literatura infantil y juvenil. \u201cHicieron un rinc\u00f3n con alfombras y almohadones, y pusieron a disposici\u00f3n la bibliograf\u00eda sobre temas de sexualidad, diversidad y g\u00e9neros\u201d, dijo la coordinadora del equipo ESI. Adem\u00e1s, la radio de la UNAHUR transmiti\u00f3 en vivo durante la feria. Por \u00faltimo, el movimiento federal XM\u00e1sESI cont\u00f3 con un stand. \u201cLa gente pasaba y escrib\u00eda por qu\u00e9 era importante tener m\u00e1s ESI en banderines que luego se colgaban\u201d, narr\u00f3 Lavari.<\/p>\n\n\n\n<p>El encuentro virtual desarrollado el 13 de noviembre estuvo a cargo del <strong>Movimiento Federal xM\u00e1sESI<\/strong>, conformado el pasado 18 de octubre. Se trata de un colectivo que nuclea <strong>docentes<\/strong> de todos los niveles y modalidades del sistema educativo, <strong>sindicatos, instancias de los gobiernos nacional y provinciales, periodistas, profesionales, militantes de organizaciones sociales, educadoras populares y promotoras territoriales de g\u00e9nero y diversidad<\/strong>. El equipo ESI de UNAHUR tambi\u00e9n integra este espacio que re\u00fane representantes en todo el territorio nacional.<\/p>\n\n\n\n<p>\u201cLa ESI es un proyecto de justicia e igualdad para la mejora de la calidad de vida de todas las personas\u201d, dec\u00eda el documento que anunciaba la conformaci\u00f3n del colectivo. \u201c<strong>Nos organizamos para compartir nuestras experiencias en el despliegue territorial de la ESI<\/strong>\u201d, agregaba. &nbsp;<\/p>\n\n\n\n<p><strong>Graciela Morgade<\/strong>, integrante del colectivo de investigaci\u00f3n Mariposas Mirabal de la Facultad de Filosof\u00eda y Letras (UBA), estuvo a cargo de la presentaci\u00f3n de la campa\u00f1a <strong>Democracia y ESI.&nbsp; 40 a\u00f1os, 40 razones. <\/strong>La actividad virtual de lanzamiento cont\u00f3 con la presencia de referentes de organizaciones sociales, de la educaci\u00f3n, del movimiento feminista y LGTTBIQA+, antirracistas, estudiantiles, artistas y fue transmitida en vivo por el canal de Youtube del Movimiento.<\/p>\n\n\n\n<p>\u201c40 a\u00f1os de democracia ininterrumpida y <strong>40 razones para defender y extender la ESI como un pol\u00edtica p\u00fablica, como un derecho y como un proyecto educativo de justicia social e igualdad<\/strong>\u201d, introdujo Morgade. Luego dej\u00f3 lugar para que distintas voces de todo el pa\u00eds se refirieran a aspectos nodales de la campa\u00f1a.<\/p>\n\n\n\n<p>El lanzamiento est\u00e1 disponible en:<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.youtube.com\/watch?v=iVF45bcfpWM\n<\/div><\/figure>\n\n\n\n<p>@AAUNAHUR<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El s\u00e1bado 11 de noviembre se desarroll\u00f3 la Feria ESI, a cargo del Equipo ESI de la Universidad Nacional de Hurlingham (UNAHUR). Tal como sucedi\u00f3 en julio de 2023, se compartieron m\u00e1s de cien propuestas l\u00fadicas, intervenciones art\u00edsticas y producciones realizadas por estudiantes. Adem\u00e1s, el lunes 13 de noviembre, el Movimiento Federal XM\u00e1sESI present\u00f3 la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3304,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[7],"tags":[648,649,62,560,108,650,142,647],"class_list":["post-3303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-40-anos","tag-40-razones","tag-esi","tag-feria-esi","tag-mariana-lavari","tag-nancy-lopez-gota","tag-universidad-nacional-de-hurlingham","tag-xmasesi"],"_links":{"self":[{"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/3303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=3303"}],"version-history":[{"count":1,"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/3303\/revisions"}],"predecessor-version":[{"id":3305,"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/3303\/revisions\/3305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/3304"}],"wp:attachment":[{"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=3303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=3303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aulaabierta.unahur.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=3303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}